{"id":239377,"date":"2019-05-30T14:49:52","date_gmt":"2019-05-30T14:49:52","guid":{"rendered":"https:\/\/stage.fincasolmark.com\/wpfs\/?post_type=project&#038;p=239377"},"modified":"2026-08-13T13:37:02","modified_gmt":"2026-08-13T11:37:02","slug":"caminito-del-rey","status":"publish","type":"project","link":"https:\/\/stage.fincasolmark.com\/es\/project\/caminito-del-rey\/","title":{"rendered":"Caminito del Rey"},"content":{"rendered":"\n<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_0 et_pb_row et_block_row\"><div class=\"et_pb_column_0 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h1><strong>Caminito del Rey<\/strong><\/h1>\n<\/div><\/div><div class=\"et_pb_divider_0 et_pb_divider_hidden et_pb_space et_pb_divider_position_top et_animated et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>El <strong>Caminito del Rey<\/strong>\u00a0es un paso construido en las paredes del desfiladero de los Gaitanes, entre los t\u00e9rminos municipales de Ardales, \u00c1lora y Antequera, en la\u00a0provincia de M\u00e1laga. Se trata de una pasarela peatonal de m\u00e1s de 3 kil\u00f3metros (adem\u00e1s de 4,8 kil\u00f3metros de accesos), adosada a la roca en el interior de un ca\u00f1\u00f3n, con tramos de una anchura de apenas 1 metro, colgando hasta 105 metros de altura sobre el r\u00edo, en unas paredes casi verticales. Se pueden realizar excursiones previa reserva y se aconseja sacar las entradas con meses de antelaci\u00f3n, dada su gran demanda tur\u00edstica.<\/p>\n<\/div><\/div><\/div><div class=\"et_pb_column_1 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_image_0 et_pb_image et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/stage.fincasolmark.com\/wp-content\/uploads\/2019\/05\/finca_solmark_carratraca_caminito_rey.jpg\" title=\"Caminito del Rey\" width=\"600\" height=\"360\" srcset=\"https:\/\/stage.fincasolmark.com\/wp-content\/uploads\/2019\/05\/finca_solmark_carratraca_caminito_rey.jpg 600w\" sizes=\"(max-width: 600px) 100vw, 600px\" class=\"wp-image-238628\" \/><\/span><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":238628,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"project_category":[62],"project_tag":[],"class_list":["post-239377","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-rutas"],"_links":{"self":[{"href":"https:\/\/stage.fincasolmark.com\/es\/wp-json\/wp\/v2\/project\/239377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.fincasolmark.com\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/stage.fincasolmark.com\/es\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/stage.fincasolmark.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stage.fincasolmark.com\/es\/wp-json\/wp\/v2\/comments?post=239377"}],"version-history":[{"count":1,"href":"https:\/\/stage.fincasolmark.com\/es\/wp-json\/wp\/v2\/project\/239377\/revisions"}],"predecessor-version":[{"id":380793,"href":"https:\/\/stage.fincasolmark.com\/es\/wp-json\/wp\/v2\/project\/239377\/revisions\/380793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stage.fincasolmark.com\/es\/wp-json\/wp\/v2\/media\/238628"}],"wp:attachment":[{"href":"https:\/\/stage.fincasolmark.com\/es\/wp-json\/wp\/v2\/media?parent=239377"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/stage.fincasolmark.com\/es\/wp-json\/wp\/v2\/project_category?post=239377"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/stage.fincasolmark.com\/es\/wp-json\/wp\/v2\/project_tag?post=239377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}